{"id":182,"count":0,"description":"","link":"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/","name":"District heating","slug":"district-heating","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>District heating Archive - Fichtner Connected<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"District heating Archive - Fichtner Connected\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/\" \/>\n<meta property=\"og:site_name\" content=\"Fichtner Connected\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/en\\\/tag\\\/district-heating\\\/\",\"url\":\"https:\\\/\\\/blog.fichtner.de\\\/en\\\/tag\\\/district-heating\\\/\",\"name\":\"District heating Archive - Fichtner Connected\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/en\\\/tag\\\/district-heating\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/en\\\/tag\\\/district-heating\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.fichtner.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"District heating\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/#website\",\"url\":\"https:\\\/\\\/blog.fichtner.de\\\/\",\"name\":\"Fichtner Connected\",\"description\":\"Willkommen bei FICHTNER CONNECTED, dem Blog der Fichtner-Gruppe\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.fichtner.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/#organization\",\"name\":\"Fichtner Connected\",\"url\":\"https:\\\/\\\/blog.fichtner.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.fichtner.de\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo_745_186_inv.png\",\"contentUrl\":\"https:\\\/\\\/blog.fichtner.de\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo_745_186_inv.png\",\"width\":745,\"height\":186,\"caption\":\"Fichtner Connected\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.fichtner.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fichtner\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"District heating Archive - Fichtner Connected","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/","og_locale":"en_US","og_type":"article","og_title":"District heating Archive - Fichtner Connected","og_url":"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/","og_site_name":"Fichtner Connected","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/","url":"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/","name":"District heating Archive - Fichtner Connected","isPartOf":{"@id":"https:\/\/blog.fichtner.de\/#website"},"breadcrumb":{"@id":"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.fichtner.de\/en\/tag\/district-heating\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.fichtner.de\/en\/"},{"@type":"ListItem","position":2,"name":"District heating"}]},{"@type":"WebSite","@id":"https:\/\/blog.fichtner.de\/#website","url":"https:\/\/blog.fichtner.de\/","name":"Fichtner Connected","description":"Willkommen bei FICHTNER CONNECTED, dem Blog der Fichtner-Gruppe","publisher":{"@id":"https:\/\/blog.fichtner.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.fichtner.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.fichtner.de\/#organization","name":"Fichtner Connected","url":"https:\/\/blog.fichtner.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.fichtner.de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.fichtner.de\/wp-content\/uploads\/2023\/05\/logo_745_186_inv.png","contentUrl":"https:\/\/blog.fichtner.de\/wp-content\/uploads\/2023\/05\/logo_745_186_inv.png","width":745,"height":186,"caption":"Fichtner Connected"},"image":{"@id":"https:\/\/blog.fichtner.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/fichtner"]}]}},"_links":{"self":[{"href":"https:\/\/blog.fichtner.de\/en\/wp-json\/wp\/v2\/tags\/182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.fichtner.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.fichtner.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.fichtner.de\/en\/wp-json\/wp\/v2\/posts?tags=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}